{"id":14,"count":57,"description":"","link":"https:\/\/www.skolamichael.cz\/en\/category\/aktualne\/akce\/","name":"Akce","slug":"akce","taxonomy":"category","parent":3,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Akce Archivy | MICHAEL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.skolamichael.cz\/en\/category\/aktualne\/akce\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Akce Archivy | MICHAEL\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.skolamichael.cz\/en\/category\/aktualne\/akce\/\" \/>\n<meta property=\"og:site_name\" content=\"MICHAEL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.skolamichael.cz\\\/en\\\/category\\\/aktualne\\\/akce\\\/\",\"url\":\"https:\\\/\\\/www.skolamichael.cz\\\/en\\\/category\\\/aktualne\\\/akce\\\/\",\"name\":\"Akce Archivy | MICHAEL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.skolamichael.cz\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.skolamichael.cz\\\/en\\\/category\\\/aktualne\\\/akce\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.skolamichael.cz\\\/en\\\/category\\\/aktualne\\\/akce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\\\/\\\/www.skolamichael.cz\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actual\",\"item\":\"https:\\\/\\\/www.skolamichael.cz\\\/en\\\/category\\\/actual\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Akce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.skolamichael.cz\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.skolamichael.cz\\\/en\\\/\",\"name\":\"MICHAEL\",\"description\":\"St\u0159edn\u00ed \u0161kola, Gymn\u00e1zium a Vy\u0161\u0161\u00ed odborn\u00e1 \u0161kola\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.skolamichael.cz\\\/en\\\/#organization\"},\"alternateName\":\"St\u0159edn\u00ed \u0161kola, Gymn\u00e1zium a Vy\u0161\u0161\u00ed odborn\u00e1 \u0161kola\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.skolamichael.cz\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.skolamichael.cz\\\/en\\\/#organization\",\"name\":\"Michael \u2013 St\u0159edn\u00ed \u0161kola, Gymn\u00e1zium a Vy\u0161\u0161\u00ed odborn\u00e1 \u0161kola, s.r.o.\",\"url\":\"https:\\\/\\\/www.skolamichael.cz\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.skolamichael.cz\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.skolamichael.cz\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo_michael_final_ctverec1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.skolamichael.cz\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo_michael_final_ctverec1-1.jpg\",\"width\":400,\"height\":400,\"caption\":\"Michael \u2013 St\u0159edn\u00ed \u0161kola, Gymn\u00e1zium a Vy\u0161\u0161\u00ed odborn\u00e1 \u0161kola, s.r.o.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.skolamichael.cz\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/skolamichael\",\"https:\\\/\\\/www.instagram.com\\\/skola_michael\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Akce Archivy | MICHAEL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.skolamichael.cz\/en\/category\/aktualne\/akce\/","og_locale":"en_US","og_type":"article","og_title":"Akce Archivy | MICHAEL","og_url":"https:\/\/www.skolamichael.cz\/en\/category\/aktualne\/akce\/","og_site_name":"MICHAEL","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.skolamichael.cz\/en\/category\/aktualne\/akce\/","url":"https:\/\/www.skolamichael.cz\/en\/category\/aktualne\/akce\/","name":"Akce Archivy | MICHAEL","isPartOf":{"@id":"https:\/\/www.skolamichael.cz\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.skolamichael.cz\/en\/category\/aktualne\/akce\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.skolamichael.cz\/en\/category\/aktualne\/akce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/www.skolamichael.cz\/en\/"},{"@type":"ListItem","position":2,"name":"Actual","item":"https:\/\/www.skolamichael.cz\/en\/category\/actual\/"},{"@type":"ListItem","position":3,"name":"Akce"}]},{"@type":"WebSite","@id":"https:\/\/www.skolamichael.cz\/en\/#website","url":"https:\/\/www.skolamichael.cz\/en\/","name":"MICHAEL","description":"St\u0159edn\u00ed \u0161kola, Gymn\u00e1zium a Vy\u0161\u0161\u00ed odborn\u00e1 \u0161kola","publisher":{"@id":"https:\/\/www.skolamichael.cz\/en\/#organization"},"alternateName":"St\u0159edn\u00ed \u0161kola, Gymn\u00e1zium a Vy\u0161\u0161\u00ed odborn\u00e1 \u0161kola","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.skolamichael.cz\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.skolamichael.cz\/en\/#organization","name":"Michael \u2013 St\u0159edn\u00ed \u0161kola, Gymn\u00e1zium a Vy\u0161\u0161\u00ed odborn\u00e1 \u0161kola, s.r.o.","url":"https:\/\/www.skolamichael.cz\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.skolamichael.cz\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.skolamichael.cz\/wp-content\/uploads\/2019\/03\/logo_michael_final_ctverec1-1.jpg","contentUrl":"https:\/\/www.skolamichael.cz\/wp-content\/uploads\/2019\/03\/logo_michael_final_ctverec1-1.jpg","width":400,"height":400,"caption":"Michael \u2013 St\u0159edn\u00ed \u0161kola, Gymn\u00e1zium a Vy\u0161\u0161\u00ed odborn\u00e1 \u0161kola, s.r.o."},"image":{"@id":"https:\/\/www.skolamichael.cz\/en\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/skolamichael","https:\/\/www.instagram.com\/skola_michael\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.skolamichael.cz\/en\/wp-json\/wp\/v2\/categories\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.skolamichael.cz\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.skolamichael.cz\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.skolamichael.cz\/en\/wp-json\/wp\/v2\/categories\/3"}],"wp:post_type":[{"href":"https:\/\/www.skolamichael.cz\/en\/wp-json\/wp\/v2\/posts?categories=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}